{"id":1425,"date":"2024-09-19T14:36:42","date_gmt":"2024-09-19T19:36:42","guid":{"rendered":"https:\/\/ucentral.org\/informativo\/?p=1425"},"modified":"2024-09-19T14:36:43","modified_gmt":"2024-09-19T19:36:43","slug":"docentes-de-la-facultad-de-ciencias-participaran-en-el-xx-foro-internacional-del-emprendedor","status":"publish","type":"post","link":"https:\/\/ucentral.org\/informativo\/index.php\/2024\/09\/19\/docentes-de-la-facultad-de-ciencias-participaran-en-el-xx-foro-internacional-del-emprendedor\/","title":{"rendered":"Docentes de la Facultad de Ciencias participar\u00e1n en el XX Foro Internacional del Emprendedor"},"content":{"rendered":"\n<p>Nos complace informar y felicitar a nuestros docentes de la Facultad de Ciencias, liderados por el Matem\u00e1tico Luis Castillo, cuya ponencia ha sido aceptada en el XX Foro Internacional del Emprendedor. Este evento, organizado por el Observatorio de la PyME de la Universidad Andina Sim\u00f3n Bol\u00edvar, Sede Ecuador, se centrar\u00e1 en el tema &#8220;Innovaci\u00f3n verde, disrupci\u00f3n tecnol\u00f3gica, financiamiento estrat\u00e9gico y sectores emergentes en el emprendimiento y las MIPYME&#8221;. <\/p>\n\n\n\n<p>La participaci\u00f3n de nuestros docentes en este foro internacional proyecta a la Facultad de Ciencias como un centro de Investigaci\u00f3n e Innovaci\u00f3n.<\/p>\n\n\n\n<p>Estamos seguros de que su contribuci\u00f3n plantear\u00e1 elementos y metodolog\u00edas que se pueden aplicar en el an\u00e1lisis del emprendimiento en las micro, peque\u00f1as y medianas empresas (MiPyMEs) que son un factor importante en el desarrollo de oportunidades sociales y econ\u00f3micas.<\/p>\n\n\n\n<p class=\"has-text-align-center has-vivid-cyan-blue-color has-text-color has-link-color has-large-font-size wp-elements-13e88b9afca44a6994a1ddd074b793df\"><strong>\u00a1hacemos ciencia!<\/strong><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"372\" height=\"371\" src=\"https:\/\/ucentral.org\/informativo\/wp-content\/uploads\/2024\/08\/logoFCiencias-Transparente-Pequeno.png\" alt=\"\" class=\"wp-image-1379\" srcset=\"https:\/\/ucentral.org\/informativo\/wp-content\/uploads\/2024\/08\/logoFCiencias-Transparente-Pequeno.png 372w, https:\/\/ucentral.org\/informativo\/wp-content\/uploads\/2024\/08\/logoFCiencias-Transparente-Pequeno-300x300.png 300w, https:\/\/ucentral.org\/informativo\/wp-content\/uploads\/2024\/08\/logoFCiencias-Transparente-Pequeno-150x150.png 150w\" sizes=\"auto, (max-width: 372px) 100vw, 372px\" \/><\/figure>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Nos complace informar y felicitar a nuestros docentes de la Facultad de Ciencias, liderados por el Matem\u00e1tico Luis Castillo, cuya ponencia ha sido aceptada en el XX Foro Internacional del Emprendedor. Este evento, organizado por el Observatorio de la PyME de la Universidad Andina Sim\u00f3n Bol\u00edvar, Sede Ecuador, se centrar\u00e1 en el tema &#8220;Innovaci\u00f3n verde, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1426,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[112,164,41,6],"tags":[84,313],"class_list":["post-1425","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ciencia-central","category-eventos","category-investigacion","category-noticias","tag-foro","tag-pyme"],"_links":{"self":[{"href":"https:\/\/ucentral.org\/informativo\/index.php\/wp-json\/wp\/v2\/posts\/1425","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ucentral.org\/informativo\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ucentral.org\/informativo\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ucentral.org\/informativo\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ucentral.org\/informativo\/index.php\/wp-json\/wp\/v2\/comments?post=1425"}],"version-history":[{"count":1,"href":"https:\/\/ucentral.org\/informativo\/index.php\/wp-json\/wp\/v2\/posts\/1425\/revisions"}],"predecessor-version":[{"id":1427,"href":"https:\/\/ucentral.org\/informativo\/index.php\/wp-json\/wp\/v2\/posts\/1425\/revisions\/1427"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ucentral.org\/informativo\/index.php\/wp-json\/wp\/v2\/media\/1426"}],"wp:attachment":[{"href":"https:\/\/ucentral.org\/informativo\/index.php\/wp-json\/wp\/v2\/media?parent=1425"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ucentral.org\/informativo\/index.php\/wp-json\/wp\/v2\/categories?post=1425"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ucentral.org\/informativo\/index.php\/wp-json\/wp\/v2\/tags?post=1425"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}