{"id":6745,"date":"2026-05-11T19:02:43","date_gmt":"2026-05-12T00:02:43","guid":{"rendered":"https:\/\/ucentral.org\/informativo\/?p=6745"},"modified":"2026-05-11T19:23:52","modified_gmt":"2026-05-12T00:23:52","slug":"cduque01","status":"publish","type":"post","link":"https:\/\/ucentral.org\/informativo\/index.php\/2026\/05\/11\/cduque01\/","title":{"rendered":"Facultad de Ciencias aporta a la capacitaci\u00f3n en Inteligencia Artificial del personal rural en salud"},"content":{"rendered":"\n<p>Con el prop\u00f3sito de fortalecer la calidad de la atenci\u00f3n brindada a la poblaci\u00f3n adulta mayor, el <strong>Ing. Carlos Eduardo Duque<\/strong> docente de la <strong>Facultad de Ciencias de la Universidad Central del Ecuador<\/strong> particip\u00f3 en las jornadas de capacitaci\u00f3n sobre <strong><strong>inteligencia artificial aplicada al \u00e1mbito m\u00e9dico<\/strong><\/strong> dirigidas al personal rural de los Centros de Salud de las Oficinas T\u00e9cnicas 1, 2, 3 y 5 del Distrito 17D03.<\/p>\n\n\n\n<p>El evento, organizado por el <strong>Hospital del Adulto Mayor<\/strong>, se desarroll\u00f3 los d\u00edas <strong>16 y 17 de abril de 2026<\/strong>, orientada a fortalecer las competencias del talento humano en salud frente a los desaf\u00edos del envejecimiento poblacional y la innovaci\u00f3n tecnol\u00f3gica.<\/p>\n\n\n\n<p class=\"has-text-align-center has-vivid-cyan-blue-color has-text-color has-link-color has-medium-font-size wp-elements-9c64a8860b184f875c4780ed3b26fcbc\">\u00a1UCETech de la Facultad de Ciencias comprometida con el desarrollo cient\u00edfico y social del pa\u00eds!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con el prop\u00f3sito de fortalecer la calidad de la atenci\u00f3n brindada a la poblaci\u00f3n adulta mayor, el Ing. Carlos Eduardo Duque docente de la Facultad de Ciencias de la Universidad Central del Ecuador particip\u00f3 en las jornadas de capacitaci\u00f3n sobre inteligencia artificial aplicada al \u00e1mbito m\u00e9dico dirigidas al personal rural de los Centros de Salud [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":6746,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[112,34,164,6,384],"tags":[161,401,334],"class_list":["post-6745","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ciencia-central","category-docentes","category-eventos","category-noticias","category-ucetech","tag-ciencia-central","tag-ia","tag-ucetech"],"_links":{"self":[{"href":"https:\/\/ucentral.org\/informativo\/index.php\/wp-json\/wp\/v2\/posts\/6745","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ucentral.org\/informativo\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ucentral.org\/informativo\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ucentral.org\/informativo\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ucentral.org\/informativo\/index.php\/wp-json\/wp\/v2\/comments?post=6745"}],"version-history":[{"count":2,"href":"https:\/\/ucentral.org\/informativo\/index.php\/wp-json\/wp\/v2\/posts\/6745\/revisions"}],"predecessor-version":[{"id":6748,"href":"https:\/\/ucentral.org\/informativo\/index.php\/wp-json\/wp\/v2\/posts\/6745\/revisions\/6748"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ucentral.org\/informativo\/index.php\/wp-json\/wp\/v2\/media\/6746"}],"wp:attachment":[{"href":"https:\/\/ucentral.org\/informativo\/index.php\/wp-json\/wp\/v2\/media?parent=6745"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ucentral.org\/informativo\/index.php\/wp-json\/wp\/v2\/categories?post=6745"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ucentral.org\/informativo\/index.php\/wp-json\/wp\/v2\/tags?post=6745"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}